{"id":2753,"date":"2014-11-20T13:36:58","date_gmt":"2014-11-20T13:36:58","guid":{"rendered":"http:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png"},"modified":"2014-11-20T13:36:58","modified_gmt":"2014-11-20T13:36:58","slug":"botella3-2","status":"inherit","type":"attachment","link":"https:\/\/www.canbonastre.com\/en\/botella3-2\/","title":{"rendered":"Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-2753","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine -\" \/>\n<meta property=\"og:description\" content=\"Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png\",\"url\":\"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png\",\"name\":\"Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine -\",\"isPartOf\":{\"@id\":\"https:\/\/www.canbonastre.com\/en\/#website\"},\"datePublished\":\"2014-11-20T13:36:58+00:00\",\"dateModified\":\"2014-11-20T13:36:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.canbonastre.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.canbonastre.com\/en\/#website\",\"url\":\"https:\/\/www.canbonastre.com\/en\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.canbonastre.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png","og_locale":"en_US","og_type":"article","og_title":"Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine -","og_description":"Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine","og_url":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png","og_image":[{"width":300,"height":600,"url":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png","url":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png","name":"Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine -","isPartOf":{"@id":"https:\/\/www.canbonastre.com\/en\/#website"},"datePublished":"2014-11-20T13:36:58+00:00","dateModified":"2014-11-20T13:36:58+00:00","breadcrumb":{"@id":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.canbonastre.com\/en\/"},{"@type":"ListItem","position":2,"name":"Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine"}]},{"@type":"WebSite","@id":"https:\/\/www.canbonastre.com\/en\/#website","url":"https:\/\/www.canbonastre.com\/en\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.canbonastre.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-0\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"300\" src=\"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3-150x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3-150x300.png 150w, https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Vino Tinto Can Bonastre Pinot Noir Penedes Red Wine<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":300,"height":600,"file":"2014\/11\/botella3.png","sizes":{"thumbnail":{"file":"botella3-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3-150x150.png"},"medium":{"file":"botella3-150x300.png","width":150,"height":300,"mime_type":"image\/png","source_url":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3-150x300.png"},"full":{"file":"botella3.png","width":300,"height":600,"mime_type":"image\/png","source_url":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":null,"source_url":"https:\/\/www.canbonastre.com\/wp-content\/uploads\/2014\/11\/botella3.png","_links":{"self":[{"href":"https:\/\/www.canbonastre.com\/en\/wp-json\/wp\/v2\/media\/2753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.canbonastre.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.canbonastre.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.canbonastre.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.canbonastre.com\/en\/wp-json\/wp\/v2\/comments?post=2753"}]}}